{"id":85,"count":1,"description":"","link":"https:\/\/paroissesainte-famille.org\/bienvenue\/tag\/verite\/","name":"v\u00e9rit\u00e9","slug":"verite","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/tags\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/posts?tags=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}