{"id":12408,"date":"2024-03-09T13:11:58","date_gmt":"2024-03-09T18:11:58","guid":{"rendered":"https:\/\/paroissesainte-famille.org\/bienvenue\/?p=12408"},"modified":"2024-03-09T13:28:44","modified_gmt":"2024-03-09T18:28:44","slug":"autochtones-et-allochtones-reunis-pour-regarder-vers-lavenir","status":"publish","type":"post","link":"https:\/\/paroissesainte-famille.org\/bienvenue\/2024\/03\/09\/autochtones-et-allochtones-reunis-pour-regarder-vers-lavenir\/","title":{"rendered":"Ensemble, regarder vers l\u2019avenir"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:47% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"558\" height=\"419\" src=\"https:\/\/paroissesainte-famille.org\/wp-content\/uploads\/2024\/03\/Autochtones-et-allochtones-reunis.jpg\" alt=\"\" class=\"wp-image-12412 size-full\" srcset=\"https:\/\/paroissesainte-famille.org\/wp-content\/uploads\/2024\/03\/Autochtones-et-allochtones-reunis.jpg 558w, https:\/\/paroissesainte-famille.org\/wp-content\/uploads\/2024\/03\/Autochtones-et-allochtones-reunis-300x225.jpg 300w\" sizes=\"auto, (max-width: 558px) 100vw, 558px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c1dbb8d586cf051c1ca6949d191c810d wp-block-paragraph\">Notre soeur Renelle a particip\u00e9, les 5 et 6 mars derniers, \u00e0 Trois-Rivi\u00e8res, \u00ab un \u00e9v\u00e9nement r\u00e9unissant pr\u00e8s de 150 personnes, dont des membres de communaut\u00e9s chr\u00e9tiennes autochtones, des intervenantes et intervenants pastoraux en milieu autochtone et les \u00e9v\u00eaques du Qu\u00e9bec. Sur les onze nations autochtones que compte le Qu\u00e9bec, huit nations \u00e9taient repr\u00e9sent\u00e9es. \u00bb <\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-69eb38f1c3dd208dce01d1a73e397871 wp-block-paragraph\">Ayant comme th\u00e8me : \u00ab <strong>Pour une conversion de notre agir pastoral en milieu autochtone: l\u2019\u00e9coute au c\u0153ur de la pr\u00e9sence<\/strong> \u00bb, cette rencontre avait pour but de permettre aux gens de prendre le temps de mieux se conna\u00eetre, de discuter, de r\u00e9fl\u00e9chir ensemble sur l\u2019avenir de la pr\u00e9sence pastorale en milieu autochtone et d\u2019entendre diverses prises de bres des Premiers Peuples.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f722332499c690db8308aa00c66cf7b9 wp-block-paragraph\">Int\u00e9ress\u00e9s \u00e0 en savoir plus ? Je vous invite \u00e0 lire l&rsquo;article de Jean Gagn\u00e9, responsable des communications du dioc\u00e8se de Chicoutimi. Il est important que chacun et chacune des disciples de J\u00e9sus de notre communaut\u00e9 se mette \u00e0 l&rsquo;\u00e9coute de l&rsquo;Esprit qui nous parle pour d\u00e9couvrir ce qu&rsquo;il nous inspire comme agir \u00e0 propos de la pr\u00e9sence des Autochtones dans notre propre r\u00e9gion.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 has-custom-font-size has-medium-font-size\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/paroissesainte-famille.org\/bienvenue\/2024\/03\/09\/autochtones-et-allochtones-reunis-pour-regarder-vers-lavenir\/\" style=\"border-radius:14px;background-color:#1b2c94\">Lire l&rsquo;article<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Notre soeur Renelle a particip\u00e9, les 5 et 6 mars derniers, \u00e0 Trois-Rivi\u00e8res, \u00ab un \u00e9v\u00e9nement r\u00e9unissant pr\u00e8s de 150 personnes, dont des membres de communaut\u00e9s chr\u00e9tiennes autochtones, des intervenantes et intervenants pastoraux en milieu autochtone et les \u00e9v\u00eaques du &hellip; <a href=\"https:\/\/paroissesainte-famille.org\/bienvenue\/2024\/03\/09\/autochtones-et-allochtones-reunis-pour-regarder-vers-lavenir\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[],"class_list":["post-12408","post","type-post","status-publish","format-standard","hentry","category-mission"],"_links":{"self":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/posts\/12408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/comments?post=12408"}],"version-history":[{"count":5,"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/posts\/12408\/revisions"}],"predecessor-version":[{"id":12420,"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/posts\/12408\/revisions\/12420"}],"wp:attachment":[{"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/media?parent=12408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/categories?post=12408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroissesainte-famille.org\/bienvenue\/wp-json\/wp\/v2\/tags?post=12408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}